{"id":254,"date":"2021-06-21T11:40:05","date_gmt":"2021-06-21T09:40:05","guid":{"rendered":"https:\/\/discover-culture.com\/partner\/254\/"},"modified":"2025-11-19T14:29:22","modified_gmt":"2025-11-19T12:29:22","slug":"burg-hochosterwitz","status":"publish","type":"landingpage","link":"https:\/\/discover-culture.com\/de\/partner\/burg-hochosterwitz\/","title":{"rendered":"Burg Hochosterwitz"},"content":{"rendered":"<section id='lightpress__section--block_a6d34ce4fd6350d663d05e211c6f1c70' class='lightpress__section lightpress__section--card-item-content'><div class=\"card-item\">\n  \n    <div id='lightpress__section--block_6a58006ee2f64' class='lightpress__section--content'><div class=\"content__grid content__grid--fifty-fifty\">\n    <div class=\"content__box content__box content__box--text-center\">\n                                                        <h3>Termine 2024:<\/h3>\n<ul>\n<li><strong>31.03.2024:<\/strong> Saisonstart, Wir haben wieder ge\u00f6ffnet<\/li>\n<li><strong> 01.05.2024:<\/strong> Garde Traditionstag<\/li>\n<li><strong>08.08.2024 \u2013 11.08.2024:<\/strong> Ritterfest<\/li>\n<li><strong>01.09.2024:<\/strong> Burg Kirchtag<\/li>\n<li><strong> 07. \u2013 08.12.2024:<\/strong> Adventmarkt<\/li>\n<\/ul>\n\n                                        <\/div>\n            <div class=\"content__box content__box\">\n                                                                    <img decoding=\"async\" class=\"content__image\" src=\"https:\/\/discover-culture.com\/wp-content\/uploads\/burgkirche_hochosterwitz-1.jpg\" alt=\"burgkirche hochosterwitz 1\" loading=\"lazy\">\n                                                        <\/div>\n    <\/div><\/div>\n<\/div>\n<\/section>\n\n<section id='lightpress__section--block_3970dda25d9fa4c5bb3767384d559647' class='lightpress__section lightpress__section--content-with-gallery'><h2 class=\"cwg__headline\">Historische Erlebnisse in einem der sch\u00f6nsten T\u00e4ler K\u00e4rntens<\/h2>\n<div id='lightpress__section--block_6a58006eee118' class='cwg__content lightpress__section--content'><div class=\"content__grid content__grid\">\n    <div class=\"content__box content__box--one-hundred\">\n                                                        <p>In einem der sch\u00f6nsten T\u00e4ler K\u00e4rntens erhebt sich ein 150 Meter hoher Kalksteinfelsen, der von allen umliegenden Bergen und H\u00fcgeln aus zu sehen ist. Die Berge von Friesach und dem Gurktal, der Ulrichsberg, der Magdalensberg, die Gerlitzen und die Villacher Alpe, ein Teil der Karawanken, das Hochland des Herzogtums St. Veit und die zahlreichen daneben liegenden Burgen und Ruinen (wie Mansberg, Taggenbrunn, die Kraiger Schl\u00f6sser, Nussberg, Liebenberg, Liebenfels und Karlsberg) geh\u00f6ren zur Aussicht, die dem Besucher von der Burg Hochosterwitz aus geboten wird.<\/p>\n\n                                        <\/div>\n    <\/div><\/div>\n\n<div class=\"cwg__gallery cwg__gallery--3\">\n                    <picture class=\"cwg__image\">\n            <source srcset=\"https:\/\/discover-culture.com\/wp-content\/uploads\/kapelle.webp\" type=\"image\/webp\">\n            <source srcset=\"https:\/\/discover-culture.com\/wp-content\/uploads\/kapelle.jpg\" type=\"image\/jpeg\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/discover-culture.com\/wp-content\/uploads\/kapelle.jpg\" alt=\"kapelle\">\n        <\/picture>\n                    <picture class=\"cwg__image\">\n            <source srcset=\"https:\/\/discover-culture.com\/wp-content\/uploads\/burg-hochosterwitz-oesterreich-sehenswuerdigkeiten-kaernten-e1561811176127.webp\" type=\"image\/webp\">\n            <source srcset=\"https:\/\/discover-culture.com\/wp-content\/uploads\/burg-hochosterwitz-oesterreich-sehenswuerdigkeiten-kaernten-e1561811176127.jpg\" type=\"image\/jpeg\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/discover-culture.com\/wp-content\/uploads\/burg-hochosterwitz-oesterreich-sehenswuerdigkeiten-kaernten-e1561811176127.jpg\" alt=\"burg hochosterwitz oesterreich sehenswuerdigkeiten kaernten e1561811176127\">\n        <\/picture>\n                    <picture class=\"cwg__image\">\n            <source srcset=\"https:\/\/discover-culture.com\/wp-content\/uploads\/eingang.webp\" type=\"image\/webp\">\n            <source srcset=\"https:\/\/discover-culture.com\/wp-content\/uploads\/eingang.jpg\" type=\"image\/jpeg\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/discover-culture.com\/wp-content\/uploads\/eingang.jpg\" alt=\"eingang\">\n        <\/picture>\n    <\/div><\/section>\n\n<section id='lightpress__section--block_eb7657ae1f82f0109be2512b194a6bc4' class='lightpress__section lightpress__section--content'><div class=\"content__grid content__grid\">\n    <div class=\"content__box content__box--one-hundred\">\n                                                        <p>Ein umfangreiches Kulturprogramm mit Konzerten, Bilderausstellungen und Festen l\u00e4dt den Besucher ein, die Burg in ihrer Vielf\u00e4ltigkeit zu entdecken. Im Burgrestaurant werden die Besucher mit heimischer K\u00e4rntner K\u00fcche verw\u00f6hnt. Neben dem interessanten Museum und dem kulinarischen Angebot k\u00f6nnen Sie auf der Burg auch in die Erlebniswelt des mittelalterlichen Handwerks eintauchen.<\/p>\n\n                                        <\/div>\n    <\/div><\/section>\n\n<section id='lightpress__section--block_ff15d34629fe90bc337375078a1ae9db' class='lightpress__section lightpress__section--content'><div class=\"content__grid content__grid--fifty-fifty\">\n    <div class=\"content__box content__box content__box--text-center\">\n                                                        <h3 class=\"text-image__heading\">Zur Geschichte<\/h3>\n<div class=\"text-image__excerpt\">\n<p>Seit 470 Jahren ist die Burg Hochosterwitz im Eigentum der Familie Khevenh\u00fcller. Im Jahr 1541, zuerst als Lehensrecht an den Landeshauptmann Christoph Khevenh\u00fcller vom Kaiser \u00fcbertragen, gelangte sie 1561 ins Eigentum des Landeshauptmannes Freiherr Georg Khevenh\u00fcller, der sie von 1570 bis 1586 in den heutigen Zustand ausbaute, bevor er 1587 starb.<\/p>\n<p>In seinem Testament, welches Sie auf der Burg in Stein gemei\u00dfelt sehen k\u00f6nnen, h\u00e4lt er fest, dass er die Burg zum Wohle und Schutze des Volkes gebaut habe<\/p>\n<\/div>\n\n                                        <\/div>\n            <div class=\"content__box content__box\">\n                                                                    <img decoding=\"async\" class=\"content__image\" src=\"https:\/\/discover-culture.com\/wp-content\/uploads\/Hochburg-Bildergalerie-3.jpg\" alt=\"Hochburg Bildergalerie 3\" loading=\"lazy\">\n                                                        <\/div>\n    <\/div><\/section>\n\n<section id='lightpress__section--block_70a6c043cc862b1436750e3c62a64be1' class='lightpress__section lightpress__section--content'><div class=\"content__grid content__grid--fifty-fifty\">\n    <div class=\"content__box content__box\">\n                                                    <img decoding=\"async\" class=\"content__image\" src=\"https:\/\/discover-culture.com\/wp-content\/uploads\/burg_hochosterwitz_robe.jpg\" alt=\"burg hochosterwitz robe\" loading=\"lazy\">\n                                        <\/div>\n            <div class=\"content__box content__box content__box--text-center\">\n                                                                        <h3><\/h3>\n<h3><\/h3>\n<h3><\/h3>\n<h3 class=\"text-image__heading\">Historie virtuell erleben<\/h3>\n<div class=\"text-image__excerpt\">\n<p>Von der R\u00fcstkammer, \u00fcber die Waffensammlung bis hin zur interessanten Bildersammlung aus der Renaissancezeit \u2013 all das zeugt von der Geschichte dieser einmaligen Wehranlage.<\/p>\n<p>Machen Sie sich auf eine virtuelle Wanderung und entdecken Sie gleichsam wundersch\u00f6ne Roben, historische Waffen oder Handwerksarten der Vergangenheit.<\/p>\n<p>Die majest\u00e4tische Burg Hochosterwitz l\u00e4dt ein, sie in ihrer ganzen Vielfalt zu entdecken.<\/p>\n<\/div>\n\n                                                        <\/div>\n    <\/div><\/section>","protected":false},"featured_media":321,"template":"","class_list":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Burg Hochosterwitz - Discover-Culture<\/title>\n<meta name=\"description\" content=\"In einem der sch\u00f6nsten T\u00e4ler K\u00e4rntens erhebt sich ein 150 Meter hoher Kalksteinfelsen, der von allen umliegenden Bergen aus zu sehen ist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/discover-culture.com\/de\/partner\/burg-hochosterwitz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burg Hochosterwitz\" \/>\n<meta property=\"og:description\" content=\"In einem der sch\u00f6nsten T\u00e4ler K\u00e4rntens erhebt sich ein 150 Meter hoher Kalksteinfelsen, der von allen umliegenden Bergen aus zu sehen ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/discover-culture.com\/de\/partner\/burg-hochosterwitz\/\" \/>\n<meta property=\"og:site_name\" content=\"Discover-Culture\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T12:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/discover-culture.com\/wp-content\/uploads\/Burg-Hochosterwitz-Instagram.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/\",\"url\":\"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/\",\"name\":\"Burg Hochosterwitz - Discover-Culture\",\"isPartOf\":{\"@id\":\"https:\/\/discover-culture.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/discover-culture.com\/wp-content\/uploads\/Burg-Hochosterwitz-Instagram.jpg\",\"datePublished\":\"2021-06-21T09:40:05+00:00\",\"dateModified\":\"2025-11-19T12:29:22+00:00\",\"description\":\"In einem der sch\u00f6nsten T\u00e4ler K\u00e4rntens erhebt sich ein 150 Meter hoher Kalksteinfelsen, der von allen umliegenden Bergen aus zu sehen ist.\",\"breadcrumb\":{\"@id\":\"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#primaryimage\",\"url\":\"https:\/\/discover-culture.com\/wp-content\/uploads\/Burg-Hochosterwitz-Instagram.jpg\",\"contentUrl\":\"https:\/\/discover-culture.com\/wp-content\/uploads\/Burg-Hochosterwitz-Instagram.jpg\",\"width\":2000,\"height\":1200,\"caption\":\"Burg Hochosterwitz Instagram\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/discover-culture.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landingpage\",\"item\":\"https:\/\/discover-culture.com\/jp\/partner\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Burg Hochosterwitz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/discover-culture.com\/de\/#website\",\"url\":\"https:\/\/discover-culture.com\/de\/\",\"name\":\"Discover-Culture\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/discover-culture.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Burg Hochosterwitz - Discover-Culture","description":"In einem der sch\u00f6nsten T\u00e4ler K\u00e4rntens erhebt sich ein 150 Meter hoher Kalksteinfelsen, der von allen umliegenden Bergen aus zu sehen ist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/discover-culture.com\/de\/partner\/burg-hochosterwitz\/","og_locale":"de_DE","og_type":"article","og_title":"Burg Hochosterwitz","og_description":"In einem der sch\u00f6nsten T\u00e4ler K\u00e4rntens erhebt sich ein 150 Meter hoher Kalksteinfelsen, der von allen umliegenden Bergen aus zu sehen ist.","og_url":"https:\/\/discover-culture.com\/de\/partner\/burg-hochosterwitz\/","og_site_name":"Discover-Culture","article_modified_time":"2025-11-19T12:29:22+00:00","og_image":[{"width":2000,"height":1200,"url":"https:\/\/discover-culture.com\/wp-content\/uploads\/Burg-Hochosterwitz-Instagram.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/","url":"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/","name":"Burg Hochosterwitz - Discover-Culture","isPartOf":{"@id":"https:\/\/discover-culture.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#primaryimage"},"image":{"@id":"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#primaryimage"},"thumbnailUrl":"https:\/\/discover-culture.com\/wp-content\/uploads\/Burg-Hochosterwitz-Instagram.jpg","datePublished":"2021-06-21T09:40:05+00:00","dateModified":"2025-11-19T12:29:22+00:00","description":"In einem der sch\u00f6nsten T\u00e4ler K\u00e4rntens erhebt sich ein 150 Meter hoher Kalksteinfelsen, der von allen umliegenden Bergen aus zu sehen ist.","breadcrumb":{"@id":"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#primaryimage","url":"https:\/\/discover-culture.com\/wp-content\/uploads\/Burg-Hochosterwitz-Instagram.jpg","contentUrl":"https:\/\/discover-culture.com\/wp-content\/uploads\/Burg-Hochosterwitz-Instagram.jpg","width":2000,"height":1200,"caption":"Burg Hochosterwitz Instagram"},{"@type":"BreadcrumbList","@id":"https:\/\/discover-culture.com\/partner\/burg-hochosterwitz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/discover-culture.com\/"},{"@type":"ListItem","position":2,"name":"Landingpage","item":"https:\/\/discover-culture.com\/jp\/partner\/"},{"@type":"ListItem","position":3,"name":"Burg Hochosterwitz"}]},{"@type":"WebSite","@id":"https:\/\/discover-culture.com\/de\/#website","url":"https:\/\/discover-culture.com\/de\/","name":"Discover-Culture","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/discover-culture.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/discover-culture.com\/de\/wp-json\/wp\/v2\/landingpage\/254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discover-culture.com\/de\/wp-json\/wp\/v2\/landingpage"}],"about":[{"href":"https:\/\/discover-culture.com\/de\/wp-json\/wp\/v2\/types\/landingpage"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/discover-culture.com\/de\/wp-json\/wp\/v2\/media\/321"}],"wp:attachment":[{"href":"https:\/\/discover-culture.com\/de\/wp-json\/wp\/v2\/media?parent=254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}